{"id":235930,"date":"2024-06-01T08:00:56","date_gmt":"2024-06-01T06:00:56","guid":{"rendered":"https:\/\/onestep.media\/seaco-oud\/product\/oester-zeeuwse-creuse-nr2-25st\/"},"modified":"2025-07-29T15:55:41","modified_gmt":"2025-07-29T13:55:41","slug":"oester-zeeuwse-creuse-nr2-25st","status":"publish","type":"product","link":"https:\/\/onestep.media\/seaco-oud\/product\/oester-zeeuwse-creuse-nr2-25st\/","title":{"rendered":"Oester Zeeuwse creuse nr2 25st"},"content":{"rendered":"<p>De Zeeuwse creuse oester kent verschillende benamingen: bolle, holle, wilde en Japanse oester. De creuse is herkenbaar aan zijn grillige uiterlijk met een bolle en een platte zijde. Hoe lager het nummer, des te groter de oester.<\/p>\n<p>Zijn heerlijke ziltige jodiumachtige smaak dankt hij onder meer aan een algendieet en het zoutgehalte van de Oosterschelde. Ze worden verwaterd in Yerseke.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zeeuwse creuses, mandje met 25 oesters, grootte 2. (86-110g, grosse)<\/p>\n","protected":false},"featured_media":367229,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[125],"product_tag":[],"class_list":{"0":"post-235930","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-oesters","8":"first","9":"instock","10":"shipping-taxable","11":"purchasable","12":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/onestep.media\/seaco-oud\/wp-json\/wp\/v2\/product\/235930","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/onestep.media\/seaco-oud\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/onestep.media\/seaco-oud\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/onestep.media\/seaco-oud\/wp-json\/wp\/v2\/comments?post=235930"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/onestep.media\/seaco-oud\/wp-json\/wp\/v2\/media\/367229"}],"wp:attachment":[{"href":"https:\/\/onestep.media\/seaco-oud\/wp-json\/wp\/v2\/media?parent=235930"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/onestep.media\/seaco-oud\/wp-json\/wp\/v2\/product_brand?post=235930"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/onestep.media\/seaco-oud\/wp-json\/wp\/v2\/product_cat?post=235930"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/onestep.media\/seaco-oud\/wp-json\/wp\/v2\/product_tag?post=235930"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}